{"id":33201,"date":"2026-06-03T15:06:21","date_gmt":"2026-06-03T07:06:21","guid":{"rendered":"https:\/\/mantuglobal.com\/?post_type=product&#038;p=33201"},"modified":"2026-06-05T12:35:56","modified_gmt":"2026-06-05T04:35:56","slug":"gongdong-capillary-blood-collection-containers-b-type-medical-laboratory-consumable-oem-odm","status":"publish","type":"product","link":"https:\/\/mantuglobal.com\/sl\/product\/gongdong-capillary-blood-collection-containers-b-type-medical-laboratory-consumable-oem-odm\/","title":{"rendered":"Gongdong posode za zbiranje kapilarne krvi (tip B) \u2013 potro\u0161ni material za medicinske laboratorije | OEM\/ODM"},"content":{"rendered":"<h2>Pregled izdelka<\/h2>\n<p>Visoka kakovost <strong>Posode za zbiranje kapilarne krvi (tip B)<\/strong> proizvaja Gongdong. Medicinski materiali, sterilna embala\u017ea, primerna za klini\u010dno laboratorijsko in diagnosti\u010dno uporabo.<\/p>\n<h2>Klju\u010dne zna\u010dilnosti<\/h2>\n<ul>\n<li>Medicinski materiali (PET\/steklo)<\/li>\n<li>Sterilno, za enkratno uporabo<\/li>\n<li>EO steriliziran<\/li>\n<li>Na voljo je pakiranje v razsutem stanju<\/li>\n<li>Podprt OEM\/ODM<\/li>\n<\/ul>\n<p><em>Gongdong Medical \u2013 zaupajo laboratoriji po vsem svetu.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Profesionalne posode za zbiranje kapilarne krvi (b-tip) proizvajalca Gongdong. Medicinska kakovost, sterilna, za enkratno uporabo. OEM\/ODM na voljo.<\/p>","protected":false},"featured_media":33161,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[1675],"product_cat":[2038],"product_tag":[],"class_list":{"0":"post-33201","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-gongdong","7":"product_cat-laboratory-consumables-medical-laboratory","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product\/33201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/comments?post=33201"}],"version-history":[{"count":1,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product\/33201\/revisions"}],"predecessor-version":[{"id":33206,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product\/33201\/revisions\/33206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/media\/33161"}],"wp:attachment":[{"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/media?parent=33201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product_brand?post=33201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product_cat?post=33201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mantuglobal.com\/sl\/wp-json\/wp\/v2\/product_tag?post=33201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}